{"id":7105,"date":"2024-01-10T11:01:45","date_gmt":"2024-01-10T11:01:45","guid":{"rendered":"https:\/\/zentia1.wpenginepowered.com\/es-es\/?page_id=7105"},"modified":"2025-12-22T09:46:46","modified_gmt":"2025-12-22T09:46:46","slug":"la-gama-de-productos-oplia","status":"publish","type":"page","link":"https:\/\/www.zentia.com\/es-es\/la-gama-de-productos-oplia\/","title":{"rendered":"La gama de productos Oplia"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":7388,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7105","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Gama de la Familia Oplia | Zentia<\/title>\n<meta name=\"description\" content=\"Descubra posibilidades de dise\u00f1o \u00fanicas con los productos de la familia Oplia, desde acabados creativos, formas y una paleta de 35 colores. Solicite una muestra hoy.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zentia.com\/es-es\/la-gama-de-productos-oplia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Gama de la Familia Oplia | Zentia\" \/>\n<meta property=\"og:description\" content=\"Descubra posibilidades de dise\u00f1o \u00fanicas con los productos de la familia Oplia, desde acabados creativos, formas y una paleta de 35 colores. Solicite una muestra hoy.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zentia.com\/es-es\/la-gama-de-productos-oplia\/\" \/>\n<meta property=\"og:site_name\" content=\"Zentia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-22T09:46:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zentia.com\/es-es\/wp-content\/uploads\/sites\/25\/2024\/01\/Zentia-Ceiling-Tile-Oplia-hA-Office-720x720.png\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/la-gama-de-productos-oplia\\\/\",\"url\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/la-gama-de-productos-oplia\\\/\",\"name\":\"La Gama de la Familia Oplia | Zentia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/la-gama-de-productos-oplia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/la-gama-de-productos-oplia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/01\\\/Zentia-Ceiling-Tile-Oplia-hA-Office.png\",\"datePublished\":\"2024-01-10T11:01:45+00:00\",\"dateModified\":\"2025-12-22T09:46:46+00:00\",\"description\":\"Descubra posibilidades de dise\u00f1o \u00fanicas con los productos de la familia Oplia, desde acabados creativos, formas y una paleta de 35 colores. Solicite una muestra hoy.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/la-gama-de-productos-oplia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/la-gama-de-productos-oplia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/la-gama-de-productos-oplia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/01\\\/Zentia-Ceiling-Tile-Oplia-hA-Office.png\",\"contentUrl\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/01\\\/Zentia-Ceiling-Tile-Oplia-hA-Office.png\",\"width\":1800,\"height\":1013},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/la-gama-de-productos-oplia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La gama de productos Oplia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/#website\",\"url\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/\",\"name\":\"Zentia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Gama de la Familia Oplia | Zentia","description":"Descubra posibilidades de dise\u00f1o \u00fanicas con los productos de la familia Oplia, desde acabados creativos, formas y una paleta de 35 colores. Solicite una muestra hoy.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zentia.com\/es-es\/la-gama-de-productos-oplia\/","og_locale":"es_ES","og_type":"article","og_title":"La Gama de la Familia Oplia | Zentia","og_description":"Descubra posibilidades de dise\u00f1o \u00fanicas con los productos de la familia Oplia, desde acabados creativos, formas y una paleta de 35 colores. Solicite una muestra hoy.","og_url":"https:\/\/www.zentia.com\/es-es\/la-gama-de-productos-oplia\/","og_site_name":"Zentia","article_modified_time":"2025-12-22T09:46:46+00:00","og_image":[{"width":720,"height":720,"url":"https:\/\/www.zentia.com\/es-es\/wp-content\/uploads\/sites\/25\/2024\/01\/Zentia-Ceiling-Tile-Oplia-hA-Office-720x720.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zentia.com\/es-es\/la-gama-de-productos-oplia\/","url":"https:\/\/www.zentia.com\/es-es\/la-gama-de-productos-oplia\/","name":"La Gama de la Familia Oplia | Zentia","isPartOf":{"@id":"https:\/\/www.zentia.com\/es-es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zentia.com\/es-es\/la-gama-de-productos-oplia\/#primaryimage"},"image":{"@id":"https:\/\/www.zentia.com\/es-es\/la-gama-de-productos-oplia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zentia.com\/es-es\/wp-content\/uploads\/sites\/25\/2024\/01\/Zentia-Ceiling-Tile-Oplia-hA-Office.png","datePublished":"2024-01-10T11:01:45+00:00","dateModified":"2025-12-22T09:46:46+00:00","description":"Descubra posibilidades de dise\u00f1o \u00fanicas con los productos de la familia Oplia, desde acabados creativos, formas y una paleta de 35 colores. Solicite una muestra hoy.","breadcrumb":{"@id":"https:\/\/www.zentia.com\/es-es\/la-gama-de-productos-oplia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zentia.com\/es-es\/la-gama-de-productos-oplia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zentia.com\/es-es\/la-gama-de-productos-oplia\/#primaryimage","url":"https:\/\/www.zentia.com\/es-es\/wp-content\/uploads\/sites\/25\/2024\/01\/Zentia-Ceiling-Tile-Oplia-hA-Office.png","contentUrl":"https:\/\/www.zentia.com\/es-es\/wp-content\/uploads\/sites\/25\/2024\/01\/Zentia-Ceiling-Tile-Oplia-hA-Office.png","width":1800,"height":1013},{"@type":"BreadcrumbList","@id":"https:\/\/www.zentia.com\/es-es\/la-gama-de-productos-oplia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.zentia.com\/es-es\/"},{"@type":"ListItem","position":2,"name":"La gama de productos Oplia"}]},{"@type":"WebSite","@id":"https:\/\/www.zentia.com\/es-es\/#website","url":"https:\/\/www.zentia.com\/es-es\/","name":"Zentia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zentia.com\/es-es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/pages\/7105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/comments?post=7105"}],"version-history":[{"count":0,"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/pages\/7105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/media\/7388"}],"wp:attachment":[{"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/media?parent=7105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}