{"id":4581,"date":"2021-11-24T15:19:55","date_gmt":"2021-11-24T15:19:55","guid":{"rendered":"https:\/\/zentia.mediaworksdev.co.uk\/en-gb\/?p=4581"},"modified":"2025-03-11T13:36:37","modified_gmt":"2025-03-11T13:36:37","slug":"los-sitemas-entia-ayudan-velux","status":"publish","type":"post","link":"https:\/\/www.zentia.com\/es-es\/sobre-nosotros\/noticias-de-la-empresa\/los-sitemas-entia-ayudan-velux\/","title":{"rendered":"Los sitemas de Zentia ayudan a VELUX\u00ae a cumplir sus objetivos m\u00e1s ambiciosos"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[632,598,530],"class_list":["post-4581","post","type-post","status-publish","format-standard","hentry","category-case-studies","category-press-releases","category-zentia-news"],"acf":{"pinnacle_portal_only":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los sitemas de Zentia ayudan a VELUX\u00ae a cumplir sus objetivos m\u00e1s ambiciosos | Zentia<\/title>\n<meta name=\"description\" content=\"Los sistemas de techo Zentia se utilizaron en la ampliaci\u00f3n de 7,7 millones de libras de la sede central del proveedor l\u00edder mundial de soluciones de iluminaci\u00f3n natural VELUX. \u00a1Descubre m\u00e1s!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zentia.com\/es-es\/sobre-nosotros\/noticias-de-la-empresa\/los-sitemas-entia-ayudan-velux\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los sitemas de Zentia ayudan a VELUX\u00ae a cumplir sus objetivos m\u00e1s ambiciosos | Zentia\" \/>\n<meta property=\"og:description\" content=\"Los sistemas de techo Zentia se utilizaron en la ampliaci\u00f3n de 7,7 millones de libras de la sede central del proveedor l\u00edder mundial de soluciones de iluminaci\u00f3n natural VELUX. \u00a1Descubre m\u00e1s!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zentia.com\/es-es\/sobre-nosotros\/noticias-de-la-empresa\/los-sitemas-entia-ayudan-velux\/\" \/>\n<meta property=\"og:site_name\" content=\"Zentia\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-24T15:19:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-11T13:36:37+00:00\" \/>\n<meta name=\"author\" content=\"mholmes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mholmes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/sobre-nosotros\\\/noticias-de-la-empresa\\\/los-sitemas-entia-ayudan-velux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/sobre-nosotros\\\/noticias-de-la-empresa\\\/los-sitemas-entia-ayudan-velux\\\/\"},\"author\":{\"name\":\"mholmes\",\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/#\\\/schema\\\/person\\\/0fcecb1c871f9f881acd94031c251ba4\"},\"headline\":\"Los sitemas de Zentia ayudan a VELUX\u00ae a cumplir sus objetivos m\u00e1s ambiciosos\",\"datePublished\":\"2021-11-24T15:19:55+00:00\",\"dateModified\":\"2025-03-11T13:36:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/sobre-nosotros\\\/noticias-de-la-empresa\\\/los-sitemas-entia-ayudan-velux\\\/\"},\"wordCount\":14,\"articleSection\":[\"Case Studies\",\"Press Releases\",\"Zentia News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/sobre-nosotros\\\/noticias-de-la-empresa\\\/los-sitemas-entia-ayudan-velux\\\/\",\"url\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/sobre-nosotros\\\/noticias-de-la-empresa\\\/los-sitemas-entia-ayudan-velux\\\/\",\"name\":\"Los sitemas de Zentia ayudan a VELUX\u00ae a cumplir sus objetivos m\u00e1s ambiciosos | Zentia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/#website\"},\"datePublished\":\"2021-11-24T15:19:55+00:00\",\"dateModified\":\"2025-03-11T13:36:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/#\\\/schema\\\/person\\\/0fcecb1c871f9f881acd94031c251ba4\"},\"description\":\"Los sistemas de techo Zentia se utilizaron en la ampliaci\u00f3n de 7,7 millones de libras de la sede central del proveedor l\u00edder mundial de soluciones de iluminaci\u00f3n natural VELUX. \u00a1Descubre m\u00e1s!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/sobre-nosotros\\\/noticias-de-la-empresa\\\/los-sitemas-entia-ayudan-velux\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/sobre-nosotros\\\/noticias-de-la-empresa\\\/los-sitemas-entia-ayudan-velux\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/sobre-nosotros\\\/noticias-de-la-empresa\\\/los-sitemas-entia-ayudan-velux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los sitemas de Zentia ayudan a VELUX\u00ae a cumplir sus objetivos m\u00e1s ambiciosos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/#website\",\"url\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/\",\"name\":\"Zentia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zentia.com\\\/es-es\\\/#\\\/schema\\\/person\\\/0fcecb1c871f9f881acd94031c251ba4\",\"name\":\"mholmes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85b3e5443965c419b6628d727fb16b5ff25336fa8052bb1b6a18bb127289b450?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85b3e5443965c419b6628d727fb16b5ff25336fa8052bb1b6a18bb127289b450?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85b3e5443965c419b6628d727fb16b5ff25336fa8052bb1b6a18bb127289b450?s=96&d=mm&r=g\",\"caption\":\"mholmes\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los sitemas de Zentia ayudan a VELUX\u00ae a cumplir sus objetivos m\u00e1s ambiciosos | Zentia","description":"Los sistemas de techo Zentia se utilizaron en la ampliaci\u00f3n de 7,7 millones de libras de la sede central del proveedor l\u00edder mundial de soluciones de iluminaci\u00f3n natural VELUX. \u00a1Descubre m\u00e1s!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zentia.com\/es-es\/sobre-nosotros\/noticias-de-la-empresa\/los-sitemas-entia-ayudan-velux\/","og_locale":"es_ES","og_type":"article","og_title":"Los sitemas de Zentia ayudan a VELUX\u00ae a cumplir sus objetivos m\u00e1s ambiciosos | Zentia","og_description":"Los sistemas de techo Zentia se utilizaron en la ampliaci\u00f3n de 7,7 millones de libras de la sede central del proveedor l\u00edder mundial de soluciones de iluminaci\u00f3n natural VELUX. \u00a1Descubre m\u00e1s!","og_url":"https:\/\/www.zentia.com\/es-es\/sobre-nosotros\/noticias-de-la-empresa\/los-sitemas-entia-ayudan-velux\/","og_site_name":"Zentia","article_published_time":"2021-11-24T15:19:55+00:00","article_modified_time":"2025-03-11T13:36:37+00:00","author":"mholmes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mholmes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zentia.com\/es-es\/sobre-nosotros\/noticias-de-la-empresa\/los-sitemas-entia-ayudan-velux\/#article","isPartOf":{"@id":"https:\/\/www.zentia.com\/es-es\/sobre-nosotros\/noticias-de-la-empresa\/los-sitemas-entia-ayudan-velux\/"},"author":{"name":"mholmes","@id":"https:\/\/www.zentia.com\/es-es\/#\/schema\/person\/0fcecb1c871f9f881acd94031c251ba4"},"headline":"Los sitemas de Zentia ayudan a VELUX\u00ae a cumplir sus objetivos m\u00e1s ambiciosos","datePublished":"2021-11-24T15:19:55+00:00","dateModified":"2025-03-11T13:36:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zentia.com\/es-es\/sobre-nosotros\/noticias-de-la-empresa\/los-sitemas-entia-ayudan-velux\/"},"wordCount":14,"articleSection":["Case Studies","Press Releases","Zentia News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.zentia.com\/es-es\/sobre-nosotros\/noticias-de-la-empresa\/los-sitemas-entia-ayudan-velux\/","url":"https:\/\/www.zentia.com\/es-es\/sobre-nosotros\/noticias-de-la-empresa\/los-sitemas-entia-ayudan-velux\/","name":"Los sitemas de Zentia ayudan a VELUX\u00ae a cumplir sus objetivos m\u00e1s ambiciosos | Zentia","isPartOf":{"@id":"https:\/\/www.zentia.com\/es-es\/#website"},"datePublished":"2021-11-24T15:19:55+00:00","dateModified":"2025-03-11T13:36:37+00:00","author":{"@id":"https:\/\/www.zentia.com\/es-es\/#\/schema\/person\/0fcecb1c871f9f881acd94031c251ba4"},"description":"Los sistemas de techo Zentia se utilizaron en la ampliaci\u00f3n de 7,7 millones de libras de la sede central del proveedor l\u00edder mundial de soluciones de iluminaci\u00f3n natural VELUX. \u00a1Descubre m\u00e1s!","breadcrumb":{"@id":"https:\/\/www.zentia.com\/es-es\/sobre-nosotros\/noticias-de-la-empresa\/los-sitemas-entia-ayudan-velux\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zentia.com\/es-es\/sobre-nosotros\/noticias-de-la-empresa\/los-sitemas-entia-ayudan-velux\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.zentia.com\/es-es\/sobre-nosotros\/noticias-de-la-empresa\/los-sitemas-entia-ayudan-velux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.zentia.com\/es-es\/"},{"@type":"ListItem","position":2,"name":"Los sitemas de Zentia ayudan a VELUX\u00ae a cumplir sus objetivos m\u00e1s ambiciosos"}]},{"@type":"WebSite","@id":"https:\/\/www.zentia.com\/es-es\/#website","url":"https:\/\/www.zentia.com\/es-es\/","name":"Zentia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zentia.com\/es-es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.zentia.com\/es-es\/#\/schema\/person\/0fcecb1c871f9f881acd94031c251ba4","name":"mholmes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/85b3e5443965c419b6628d727fb16b5ff25336fa8052bb1b6a18bb127289b450?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/85b3e5443965c419b6628d727fb16b5ff25336fa8052bb1b6a18bb127289b450?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/85b3e5443965c419b6628d727fb16b5ff25336fa8052bb1b6a18bb127289b450?s=96&d=mm&r=g","caption":"mholmes"}}]}},"_links":{"self":[{"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/posts\/4581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/comments?post=4581"}],"version-history":[{"count":0,"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/posts\/4581\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/media?parent=4581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zentia.com\/es-es\/wp-json\/wp\/v2\/categories?post=4581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}